{"id":2714,"date":"2026-07-09T00:19:55","date_gmt":"2026-07-09T00:19:55","guid":{"rendered":"https:\/\/nmiford.co.za\/pietermaritzburg\/pre-owned-vehicles\/mg-2\/"},"modified":"2026-07-15T03:17:40","modified_gmt":"2026-07-15T03:17:40","slug":"mg-2","status":"publish","type":"pre_owned_vehicles","link":"https:\/\/nmiford.co.za\/pietermaritzburg\/pre-owned-vehicles\/mg-2\/","title":{"rendered":"MG"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-2714","pre_owned_vehicles","type-pre_owned_vehicles","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/nmiford.co.za\/pietermaritzburg\/wp-json\/wp\/v2\/pre_owned_vehicles\/2714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nmiford.co.za\/pietermaritzburg\/wp-json\/wp\/v2\/pre_owned_vehicles"}],"about":[{"href":"https:\/\/nmiford.co.za\/pietermaritzburg\/wp-json\/wp\/v2\/types\/pre_owned_vehicles"}],"wp:attachment":[{"href":"https:\/\/nmiford.co.za\/pietermaritzburg\/wp-json\/wp\/v2\/media?parent=2714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}